{"id":2568,"date":"2018-04-10T15:00:02","date_gmt":"2018-04-10T14:00:02","guid":{"rendered":"https:\/\/www.rcrflooringproducts.com\/rcr-builds-rinol-resin-flooring-systems-success-uk\/"},"modified":"2018-07-26T16:19:22","modified_gmt":"2018-07-26T15:19:22","slug":"rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni","status":"publish","type":"post","link":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/","title":{"rendered":"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni"},"content":{"rendered":"<p>Suite \u00e0 une grande r\u00e9ussite du projet initial au Royaume-Uni, RCR Flooring Products Ltd poursuit le d\u00e9veloppement de la croissance des syst\u00e8mes RINOL de rev\u00eatements de sols r\u00e9sine au Royaume-Uni.<\/p>\n<p>La marque RINOL compl\u00e8te \u00e0 la perfection la gamme de produits de rev\u00eatements de sols RCR, qui inclut \u00e9galement les joints blind\u00e9s Permaban et les durcisseurs de surface Dry-shake Rocland pour les sols en b\u00e9ton.<\/p>\n<p>\u00c9tablie sur le plan international depuis plus de 50 ans, la marque RINOL, d\u00e9tenue par la soci\u00e9t\u00e9 m\u00e8re RCR Industrial Flooring, est reconnue et respect\u00e9e pour ses syst\u00e8mes multicouches en r\u00e9sine de haute qualit\u00e9, con\u00e7us pour r\u00e9pondre avec pr\u00e9cision aux besoins de march\u00e9s importants.<\/p>\n<h3>Polyvalent et durable<\/h3>\n<p>Les syst\u00e8mes de rev\u00eatements en r\u00e9sine synth\u00e9tique sont fabriqu\u00e9s en Allemagne et en Italie, mais leur influence sur le march\u00e9 des rev\u00eatements de sols industriels ne conna\u00eet pas de fronti\u00e8res. Ils sont utilis\u00e9s dans des projets du monde entier pour des marques commerciales et industrielles importantes, comme Audi, BMW, Decathlon et Lidl.<\/p>\n<p>La majorit\u00e9 des syst\u00e8mes RINOL sont \u00e0 base de r\u00e9sine \u00e9poxy ou polyur\u00e9thane. Chaque syst\u00e8me comprend g\u00e9n\u00e9ralement deux ou trois couches, appliqu\u00e9es tour \u00e0 tour sur la surface du b\u00e9ton \u2013 un appr\u00eat, puis un compos\u00e9 de nivellement et enfin un rev\u00eatement color\u00e9. Ce processus garantit une finition de haute qualit\u00e9, durable et attrayante.<\/p>\n<p>Adapt\u00e9s aux sols industriels (pour les nouvelles constructions et les remises \u00e0 neuf), les syst\u00e8mes RINOL sont aussi indiqu\u00e9s pour les salles d\u2019exposition, les centres culturels, les \u00e9coles, les b\u00e2timents publics et les grands appartements.<\/p>\n<p>Le choix d\u2019un rev\u00eatement RINOL offre des avantages importants pour le propri\u00e9taire de l\u2019immeuble et l\u2019utilisateur, notamment une r\u00e9sistance aux produits chimiques et \u00e0 l\u2019abrasion, ainsi qu\u2019une finition esth\u00e9tique d\u00e9nu\u00e9e de joint.<\/p>\n<p>Un large \u00e9ventail de coloris RAL et NCS sont disponibles. En outre, l\u2019entreprise peut cr\u00e9er des syst\u00e8mes sp\u00e9ciaux pour r\u00e9pondre de mani\u00e8re pr\u00e9cise \u00e0 une application client, tous contr\u00f4l\u00e9s par le biais de ses proc\u00e9dures certifi\u00e9es ISO 9001.<\/p>\n<h3>Syst\u00e8mes RINOL populaires<\/h3>\n<p>Avec pr\u00e8s de 30 syst\u00e8mes au choix, les clients et prescripteurs trouveront un syst\u00e8me id\u00e9al, adapt\u00e9 \u00e0 la plupart des applications commerciales, industrielles et domestiques haut de gamme.<\/p>\n<p><a href=\"http:\/\/www.rinol.de\/fr\/content\/rinol_allrounder_ep.html\" target=\"_blank\" rel=\"noopener\">RINOL Allrounder<\/a>\u00a0est l\u2019un des choix les plus populaires pour l\u2019industrie en g\u00e9n\u00e9ral, car il peut \u00eatre utilis\u00e9 aussi bien pour les usines de fabrication et de production que pour les aires d\u2019entreposage. Extr\u00eamement durable, il offre une r\u00e9sistance adapt\u00e9e aux charges lourdes et aux chocs, ainsi qu\u2019une r\u00e9sistance \u00e9lev\u00e9e aux produits chimiques et aux abrasions. Il est en outre facile \u00e0 nettoyer et \u00e0 entretenir.<\/p>\n<p>Les zones de production d\u2019aliments et de boissons ont des exigences particuli\u00e8res en mati\u00e8re d\u2019hygi\u00e8ne et de sant\u00e9 et s\u00e9curit\u00e9, notamment en termes de facilit\u00e9 de nettoyage et une meilleure adh\u00e9rence.\u00a0<a href=\"http:\/\/www.rinol.de\/fr\/content\/rinol_crete_standard.html\" target=\"_blank\" rel=\"noopener\">RINOL Crete<\/a>\u00a0fournit tous ces param\u00e8tres, car il neutralise tout d\u00e9veloppement bact\u00e9riologique et r\u00e9siste aux acides et sels alimentaires courants ainsi qu\u2019aux eaux de javel et aux solvants. Il est conforme aux normes europ\u00e9ennes pour les usines de traitement alimentaire\u00a0; il r\u00e9siste aux charges lourdes et aux impacts ainsi qu\u2019\u00e0 des temp\u00e9ratures allant de 80\u00a0\u00b0C \u00e0 -20\u00a0\u00b0C.<\/p>\n<p><a href=\"http:\/\/www.rinol.de\/fr\/content\/rinol_qcr.html\" target=\"_blank\" rel=\"noopener\">RINOL QCR<\/a>\u00a0est le syst\u00e8me recommand\u00e9 pour les environnements pharmaceutiques et de soins de sant\u00e9, notamment dans les cliniques et les h\u00f4pitaux. Arborant une superbe finition de couleur quartz, il r\u00e9siste aux impacts et aux \u00e9raflures de faible niveau. Il est en outre facile \u00e0 nettoyer et pr\u00e9sente naturellement une surface antid\u00e9rapante.<\/p>\n<p>Pour les environnements \u00e9lectroniques et les salles blanches, <a href=\"http:\/\/www.rinol.de\/fr\/content\/rinol_conductive.html\">RINOL Conductive<\/a>\u00a0offre une finition sans joints et sans poussi\u00e8re, test\u00e9e pour la conductivit\u00e9 et les d\u00e9charges \u00e9lectrostatiques.<\/p>\n<p><a href=\"http:\/\/www.rinol.de\/fr\/content\/rinol_comfort.html\" target=\"_blank\" rel=\"noopener\">RINOL Comfort<\/a>, comme son nom l\u2019indique, est agr\u00e9able \u00e0 la circulation pi\u00e9tonne, et donc id\u00e9al pour un usage domestique haut de gamme, ainsi que pour les salles d\u2019exposition, les bureaux, les espaces de r\u00e9ception et les \u00e9coles. Gr\u00e2ce \u00e0 la bonne stabilit\u00e9 de ses couleurs, il offre un cachet esth\u00e9tique durable et fiable.<\/p>\n<p>Bon nombre d\u2019autres syst\u00e8mes sp\u00e9cialis\u00e9s sont disponibles, y compris une gamme pour les <a href=\"http:\/\/www.rinol.de\/fr\/content\/rinol_parking_os_11a.html\" target=\"_blank\" rel=\"noopener\">surfaces de parkings<\/a>.<\/p>\n<p><em>(illustr\u00e9 : RINOL Allrounder pour KIA, Mexique.)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suite \u00e0 une grande r\u00e9ussite du projet initial au Royaume-Uni, RCR Flooring Products Ltd poursuit le d\u00e9veloppement de la croissance des syst\u00e8mes RINOL de rev\u00eatements de sols r\u00e9sine au Royaume-Uni. La marque RINOL compl\u00e8te \u00e0 la perfection la gamme de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24,27],"tags":[],"class_list":["post-2568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-actualites-sur-les-produits"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni - RCR Flooring Products<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni - RCR Flooring Products\" \/>\n<meta property=\"og:description\" content=\"Suite \u00e0 une grande r\u00e9ussite du projet initial au Royaume-Uni, RCR Flooring Products Ltd poursuit le d\u00e9veloppement de la croissance des syst\u00e8mes RINOL de rev\u00eatements de sols r\u00e9sine au Royaume-Uni. La marque RINOL compl\u00e8te \u00e0 la perfection la gamme de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/\" \/>\n<meta property=\"og:site_name\" content=\"RCR Flooring Products\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-10T14:00:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-26T15:19:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Carrasco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Carrasco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/\"},\"author\":{\"name\":\"David Carrasco\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#\\\/schema\\\/person\\\/af57d49c3af993efcfbd0c929499f7bb\"},\"headline\":\"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni\",\"datePublished\":\"2018-04-10T14:00:02+00:00\",\"dateModified\":\"2018-07-26T15:19:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/\"},\"wordCount\":781,\"image\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/RINOL-Allrounder-for-KIA-Mexico.jpg\",\"articleSection\":[\"Actualit\u00e9s\",\"Actualit\u00e9s sur les produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/\",\"url\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/\",\"name\":\"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni - RCR Flooring Products\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/RINOL-Allrounder-for-KIA-Mexico.jpg\",\"datePublished\":\"2018-04-10T14:00:02+00:00\",\"dateModified\":\"2018-07-26T15:19:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#\\\/schema\\\/person\\\/af57d49c3af993efcfbd0c929499f7bb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/RINOL-Allrounder-for-KIA-Mexico.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/RINOL-Allrounder-for-KIA-Mexico.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/\",\"name\":\"RCR Flooring Products\",\"description\":\"Industrial Flooring Products\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#\\\/schema\\\/person\\\/af57d49c3af993efcfbd0c929499f7bb\",\"name\":\"David Carrasco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g\",\"caption\":\"David Carrasco\"},\"url\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/fr\\\/author\\\/david\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni - RCR Flooring Products","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/","og_locale":"fr_FR","og_type":"article","og_title":"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni - RCR Flooring Products","og_description":"Suite \u00e0 une grande r\u00e9ussite du projet initial au Royaume-Uni, RCR Flooring Products Ltd poursuit le d\u00e9veloppement de la croissance des syst\u00e8mes RINOL de rev\u00eatements de sols r\u00e9sine au Royaume-Uni. La marque RINOL compl\u00e8te \u00e0 la perfection la gamme de...","og_url":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/","og_site_name":"RCR Flooring Products","article_published_time":"2018-04-10T14:00:02+00:00","article_modified_time":"2018-07-26T15:19:22+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","type":"image\/jpeg"}],"author":"David Carrasco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"David Carrasco","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/#article","isPartOf":{"@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/"},"author":{"name":"David Carrasco","@id":"https:\/\/www.rcrflooringproducts.com\/#\/schema\/person\/af57d49c3af993efcfbd0c929499f7bb"},"headline":"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni","datePublished":"2018-04-10T14:00:02+00:00","dateModified":"2018-07-26T15:19:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/"},"wordCount":781,"image":{"@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","articleSection":["Actualit\u00e9s","Actualit\u00e9s sur les produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/","url":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/","name":"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni - RCR Flooring Products","isPartOf":{"@id":"https:\/\/www.rcrflooringproducts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/#primaryimage"},"image":{"@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","datePublished":"2018-04-10T14:00:02+00:00","dateModified":"2018-07-26T15:19:22+00:00","author":{"@id":"https:\/\/www.rcrflooringproducts.com\/#\/schema\/person\/af57d49c3af993efcfbd0c929499f7bb"},"breadcrumb":{"@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/#primaryimage","url":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","contentUrl":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.rcrflooringproducts.com\/fr\/rcr-sappuie-sur-le-succes-des-systemes-de-revetements-de-sols-en-resine-rinol-au-royaume-uni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rcrflooringproducts.com\/fr\/"},{"@type":"ListItem","position":2,"name":"RCR s\u2019appuie sur le succ\u00e8s des syst\u00e8mes de rev\u00eatements de sols en r\u00e9sine RINOL au Royaume-Uni"}]},{"@type":"WebSite","@id":"https:\/\/www.rcrflooringproducts.com\/#website","url":"https:\/\/www.rcrflooringproducts.com\/","name":"RCR Flooring Products","description":"Industrial Flooring Products","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rcrflooringproducts.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.rcrflooringproducts.com\/#\/schema\/person\/af57d49c3af993efcfbd0c929499f7bb","name":"David Carrasco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g","caption":"David Carrasco"},"url":"https:\/\/www.rcrflooringproducts.com\/fr\/author\/david\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/posts\/2568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/comments?post=2568"}],"version-history":[{"count":0,"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/posts\/2568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/media\/2554"}],"wp:attachment":[{"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/media?parent=2568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/categories?post=2568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/fr\/wp-json\/wp\/v2\/tags?post=2568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}