{"id":2687,"date":"2018-04-10T15:00:02","date_gmt":"2018-04-10T14:00:02","guid":{"rendered":"https:\/\/www.rcrflooringproducts.com\/rcr-builds-rinol-resin-flooring-systems-success-uk\/"},"modified":"2019-10-30T14:38:07","modified_gmt":"2019-10-30T14:38:07","slug":"rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf","status":"publish","type":"post","link":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/","title":{"rendered":"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf"},"content":{"rendered":"<p>Nach ersten erfolgreichen Projekten in Gro\u00dfbritannien baut RCR Flooring Products Ltd das Wachstum der Marke RINOL f\u00fcr Harzbodensysteme in Gro\u00dfbritannien weiter aus.<\/p>\n<p>Die Marke RINOL erg\u00e4nzt die Palette der Industrieb\u00f6den von RCR perfekt, zu denen auch Permaban-Panzerfugen und trocken sch\u00fcttelbare Oberfl\u00e4chenh\u00e4rter von Rocland f\u00fcr Betonb\u00f6den geh\u00f6ren.<\/p>\n<p>Die seit \u00fcber 50 Jahren international etablierte Marke RINOL &#8211; im Besitz der Muttergesellschaft RCR Industrial Flooring &#8211; ist f\u00fcr ihre hochwertigen Mehrschicht-Harzsysteme bekannt, die speziell auf die Bed\u00fcrfnisse der wichtigsten Marktsektoren zugeschnitten sind.<\/p>\n<h3>Vielseitig und langlebig<\/h3>\n<p>Die Kunstharzbeschichtungssysteme von RINOL werden in Deutschland und Italien hergestellt. Ihr Einfluss auf den Industriebodenmarkt erstreckt sich jedoch \u00fcber die ganze Welt. Sie wurden weltweit in Projekten f\u00fcr gro\u00dfe Handels- und Industriemarken wie Audi, BMW, Decathlon und Lidl eingesetzt.<\/p>\n<p>Die meisten RINOL-Systeme basieren entweder auf Epoxidharz oder Polyurethan. Jedes System besteht typischerweise aus zwei oder drei Schichten, die nacheinander auf die Betonoberfl\u00e4che aufgetragen werden &#8211; eine Grundierung, dann eine Ausgleichsmasse und schlie\u00dflich die farbige Beschichtung. Dieser Prozess sorgt f\u00fcr ein hochwertiges, langlebiges und attraktives Finish.<\/p>\n<p>Die Systeme von RINOL eignen sich nicht nur f\u00fcr Industrieb\u00f6den (sowohl f\u00fcr Neubau- als auch f\u00fcr Renovierungsarbeiten), sondern sind auch f\u00fcr Ausstellungsr\u00e4ume, Ausstellungszentren, Schulen, \u00f6ffentliche Geb\u00e4ude und gro\u00dfe Wohnungen beliebt.<\/p>\n<p>Die Wahl einer RINOL-Beschichtung bietet dem Eigent\u00fcmer und Nutzer des Geb\u00e4udes wichtige Vorteile wie chemische Best\u00e4ndigkeit, Abriebfestigkeit und ein attraktives nahtloses Finish.<\/p>\n<p>Eine breite Palette von RAL- und NCS-Farben ist verf\u00fcgbar. Dar\u00fcber hinaus kann das Unternehmen spezielle Systeme erstellen, die genau auf die Anwendung eines Kunden zugeschnitten sind &#8211; alles gesteuert durch seine ISO9001-Verfahren.<\/p>\n<h3>Beliebte RINOL-Systeme<\/h3>\n<p>Mit rund 30 verf\u00fcgbaren Systemen finden Kunden und Planer ein ideales System f\u00fcr die meisten gewerblichen, industriellen und High-End-Anwendungen im Haushalt.<\/p>\n<p>Der <a href=\"http:\/\/www.rinol.de\/de\/content\/rinol_allrounder_ep.html\" target=\"_blank\" rel=\"noopener noreferrer\">RINOL Allrounder<\/a> ist eine der beliebtesten L\u00f6sungen f\u00fcr die allgemeine Industrie, da er gleicherma\u00dfen f\u00fcr Produktionsst\u00e4tten und Produktions- und Lagerbereiche eingesetzt werden kann. Es bietet eine gute Best\u00e4ndigkeit gegen schwere Lasten und St\u00f6\u00dfe sowie eine hohe Best\u00e4ndigkeit gegen Chemikalien und Abrieb und ist daher \u00e4u\u00dferst langlebig. Au\u00dferdem ist es leicht zu reinigen und zu warten.<\/p>\n<p>In der Lebensmittel- und Getr\u00e4nkeproduktion werden besondere Anforderungen an Hygiene, Gesundheit und Sicherheit gestellt, einschlie\u00dflich einfacher Reinigung und Rutschfestigkeit. RINOL Crete bietet alles, da es der bakteriologischen Entwicklung entgegenwirkt und den \u00fcblichen S\u00e4uren und Salzen auf Lebensmittelbasis sowie Bleichmitteln und L\u00f6sungsmitteln widersteht. Es entspricht den europ\u00e4ischen Normen f\u00fcr Lebensmittelverarbeitungsbetriebe. und h\u00e4lt hohen Belastungen und St\u00f6\u00dfen sowie Temperaturen von 80 \u00b0 C bis -20 \u00b0 C stand.<\/p>\n<p>RINOL QCR ist das empfohlene System f\u00fcr pharmazeutische Anwendungen und Anwendungen im Gesundheitswesen, einschlie\u00dflich Kliniken und Krankenh\u00e4usern. Mit seiner hervorragenden Quarzfarbe widersteht es leichten St\u00f6\u00dfen und Kratzern und ist sehr pflegeleicht und nat\u00fcrlich rutschfest.<\/p>\n<p>F\u00fcr Elektronikumgebungen und Reinr\u00e4ume bietet RINOL Conductive eine nahtlose, staubfreie Oberfl\u00e4che, die auf Leitf\u00e4higkeit oder elektrostatische Entladung getestet wurde.<\/p>\n<p>RINOL Comfort ist, wie der Name schon sagt, leicht zu Fu\u00df zu erreichen und eignet sich daher ideal f\u00fcr den High-End-Haushalt sowie f\u00fcr Ausstellungsr\u00e4ume, B\u00fcros, Empfangsbereiche und Schulen. Aufgrund seiner guten Farbstabilit\u00e4t kann man sich darauf verlassen, dass es \u00e4sthetisch ansprechend bleibt.<\/p>\n<p>Viele andere Spezialsysteme sind verf\u00fcgbar, einschlie\u00dflich eines Sortiments f\u00fcr Parkfl\u00e4chen.<\/p>\n<p><em>(Bild: RINOL Allrounder f\u00fcr KIA, Mexiko.)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach ersten erfolgreichen Projekten in Gro\u00dfbritannien baut RCR Flooring Products Ltd das Wachstum der Marke RINOL f\u00fcr Harzbodensysteme in Gro\u00dfbritannien weiter aus. Die Marke RINOL erg\u00e4nzt die Palette der Industrieb\u00f6den von RCR perfekt, zu denen auch Permaban-Panzerfugen und trocken sch\u00fcttelbare&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25,38],"tags":[],"class_list":["post-2687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuesten-nachrichten","category-produktneuheiten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf - RCR Flooring Products<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf - RCR Flooring Products\" \/>\n<meta property=\"og:description\" content=\"Nach ersten erfolgreichen Projekten in Gro\u00dfbritannien baut RCR Flooring Products Ltd das Wachstum der Marke RINOL f\u00fcr Harzbodensysteme in Gro\u00dfbritannien weiter aus. Die Marke RINOL erg\u00e4nzt die Palette der Industrieb\u00f6den von RCR perfekt, zu denen auch Permaban-Panzerfugen und trocken sch\u00fcttelbare...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/\" \/>\n<meta property=\"og:site_name\" content=\"RCR Flooring Products\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-10T14:00:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-30T14:38:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Carrasco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Carrasco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/\"},\"author\":{\"name\":\"David Carrasco\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#\\\/schema\\\/person\\\/af57d49c3af993efcfbd0c929499f7bb\"},\"headline\":\"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf\",\"datePublished\":\"2018-04-10T14:00:02+00:00\",\"dateModified\":\"2019-10-30T14:38:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/\"},\"wordCount\":585,\"image\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/RINOL-Allrounder-for-KIA-Mexico.jpg\",\"articleSection\":[\"Neuesten Nachrichten\",\"Produktneuheiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/\",\"url\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/\",\"name\":\"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf - RCR Flooring Products\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/RINOL-Allrounder-for-KIA-Mexico.jpg\",\"datePublished\":\"2018-04-10T14:00:02+00:00\",\"dateModified\":\"2019-10-30T14:38:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#\\\/schema\\\/person\\\/af57d49c3af993efcfbd0c929499f7bb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/RINOL-Allrounder-for-KIA-Mexico.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/RINOL-Allrounder-for-KIA-Mexico.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/\",\"name\":\"RCR Flooring Products\",\"description\":\"Industrial Flooring Products\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/#\\\/schema\\\/person\\\/af57d49c3af993efcfbd0c929499f7bb\",\"name\":\"David Carrasco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g\",\"caption\":\"David Carrasco\"},\"url\":\"https:\\\/\\\/www.rcrflooringproducts.com\\\/de\\\/author\\\/david\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf - RCR Flooring Products","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/","og_locale":"de_DE","og_type":"article","og_title":"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf - RCR Flooring Products","og_description":"Nach ersten erfolgreichen Projekten in Gro\u00dfbritannien baut RCR Flooring Products Ltd das Wachstum der Marke RINOL f\u00fcr Harzbodensysteme in Gro\u00dfbritannien weiter aus. Die Marke RINOL erg\u00e4nzt die Palette der Industrieb\u00f6den von RCR perfekt, zu denen auch Permaban-Panzerfugen und trocken sch\u00fcttelbare...","og_url":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/","og_site_name":"RCR Flooring Products","article_published_time":"2018-04-10T14:00:02+00:00","article_modified_time":"2019-10-30T14:38:07+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","type":"image\/jpeg"}],"author":"David Carrasco","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"David Carrasco","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/#article","isPartOf":{"@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/"},"author":{"name":"David Carrasco","@id":"https:\/\/www.rcrflooringproducts.com\/#\/schema\/person\/af57d49c3af993efcfbd0c929499f7bb"},"headline":"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf","datePublished":"2018-04-10T14:00:02+00:00","dateModified":"2019-10-30T14:38:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/"},"wordCount":585,"image":{"@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","articleSection":["Neuesten Nachrichten","Produktneuheiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/","url":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/","name":"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf - RCR Flooring Products","isPartOf":{"@id":"https:\/\/www.rcrflooringproducts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/#primaryimage"},"image":{"@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","datePublished":"2018-04-10T14:00:02+00:00","dateModified":"2019-10-30T14:38:07+00:00","author":{"@id":"https:\/\/www.rcrflooringproducts.com\/#\/schema\/person\/af57d49c3af993efcfbd0c929499f7bb"},"breadcrumb":{"@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/#primaryimage","url":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","contentUrl":"https:\/\/www.rcrflooringproducts.com\/wp-content\/uploads\/2018\/03\/RINOL-Allrounder-for-KIA-Mexico.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.rcrflooringproducts.com\/de\/rcr-baut-auf-dem-erfolg-von-rinol-harzbodensystemen-in-grossbritannien-auf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rcrflooringproducts.com\/de\/"},{"@type":"ListItem","position":2,"name":"RCR baut auf dem Erfolg von RINOL-Harzbodensystemen in Gro\u00dfbritannien auf"}]},{"@type":"WebSite","@id":"https:\/\/www.rcrflooringproducts.com\/#website","url":"https:\/\/www.rcrflooringproducts.com\/","name":"RCR Flooring Products","description":"Industrial Flooring Products","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rcrflooringproducts.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.rcrflooringproducts.com\/#\/schema\/person\/af57d49c3af993efcfbd0c929499f7bb","name":"David Carrasco","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1b9163533c3472be6eda6ef76831bb0c656c8c7f191782ad9a41c213cfd3321?s=96&d=mm&r=g","caption":"David Carrasco"},"url":"https:\/\/www.rcrflooringproducts.com\/de\/author\/david\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/posts\/2687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/comments?post=2687"}],"version-history":[{"count":0,"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/posts\/2687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/media\/2555"}],"wp:attachment":[{"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/media?parent=2687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/categories?post=2687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rcrflooringproducts.com\/de\/wp-json\/wp\/v2\/tags?post=2687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}